{"id":1341,"date":"2013-06-30T10:40:49","date_gmt":"2013-06-30T08:40:49","guid":{"rendered":"http:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618.jpg"},"modified":"2013-06-30T10:40:49","modified_gmt":"2013-06-30T08:40:49","slug":"argazkia3618","status":"inherit","type":"attachment","link":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/","title":{"rendered":"Argazkia3618"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-1341","attachment","type-attachment","status-inherit","czr-hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EQUO Euskadi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EQUO Euskadi\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Argazkia3618 | EQUO Berdeak Euskadi\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2020\/03\/logoredes.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2020\/03\/logoredes.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-06-30T08:40:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-06-30T08:40:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@EquoBerdeak\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Argazkia3618 | EQUO Berdeak Euskadi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2020\/03\/logoredes.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#listItem\",\"name\":\"Argazkia3618\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#listItem\",\"position\":2,\"name\":\"Argazkia3618\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#itempage\",\"url\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/\",\"name\":\"Argazkia3618 | EQUO Berdeak Euskadi\",\"inLanguage\":\"eu-EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/author\\\/masterequo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/author\\\/masterequo\\\/#author\"},\"datePublished\":\"2013-06-30T10:40:49+02:00\",\"dateModified\":\"2013-06-30T10:40:49+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/#organization\",\"name\":\"EQUO Berdeak Euskadi\",\"description\":\"EQUO Berdeak Euskadi\",\"url\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/Argazkia3618.jpg\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/author\\\/masterequo\\\/#author\",\"url\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/author\\\/masterequo\\\/\",\"name\":\"EQUO Euskadi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/2013\\\/06\\\/30\\\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\\\/argazkia3618\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c180aa0b5f2f8c7dc8bc93fa385a33887fdcf6cfa6e9b7e6d3dd8463d22bd271?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"EQUO Euskadi\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/#website\",\"url\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/\",\"name\":\"Verdes EQUO Euskadi\",\"description\":\"EQUO Berdeak Euskadi\",\"inLanguage\":\"eu-EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/euskadi.verdesequo.es\\\/EU\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Argazkia3618 | EQUO Berdeak Euskadi","description":"","canonical_url":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/euskadi.verdesequo.es\/EU#listItem","position":1,"name":"Home","item":"https:\/\/euskadi.verdesequo.es\/EU","nextItem":{"@type":"ListItem","@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#listItem","name":"Argazkia3618"}},{"@type":"ListItem","@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#listItem","position":2,"name":"Argazkia3618","previousItem":{"@type":"ListItem","@id":"https:\/\/euskadi.verdesequo.es\/EU#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#itempage","url":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/","name":"Argazkia3618 | EQUO Berdeak Euskadi","inLanguage":"eu-EU","isPartOf":{"@id":"https:\/\/euskadi.verdesequo.es\/EU\/#website"},"breadcrumb":{"@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#breadcrumblist"},"author":{"@id":"https:\/\/euskadi.verdesequo.es\/EU\/author\/masterequo\/#author"},"creator":{"@id":"https:\/\/euskadi.verdesequo.es\/EU\/author\/masterequo\/#author"},"datePublished":"2013-06-30T10:40:49+02:00","dateModified":"2013-06-30T10:40:49+02:00"},{"@type":"Organization","@id":"https:\/\/euskadi.verdesequo.es\/EU\/#organization","name":"EQUO Berdeak Euskadi","description":"EQUO Berdeak Euskadi","url":"https:\/\/euskadi.verdesequo.es\/EU\/","logo":{"@type":"ImageObject","url":"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618.jpg","@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#organizationLogo"},"image":{"@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/euskadi.verdesequo.es\/EU\/author\/masterequo\/#author","url":"https:\/\/euskadi.verdesequo.es\/EU\/author\/masterequo\/","name":"EQUO Euskadi","image":{"@type":"ImageObject","@id":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c180aa0b5f2f8c7dc8bc93fa385a33887fdcf6cfa6e9b7e6d3dd8463d22bd271?s=96&r=g","width":96,"height":96,"caption":"EQUO Euskadi"}},{"@type":"WebSite","@id":"https:\/\/euskadi.verdesequo.es\/EU\/#website","url":"https:\/\/euskadi.verdesequo.es\/EU\/","name":"Verdes EQUO Euskadi","description":"EQUO Berdeak Euskadi","inLanguage":"eu-EU","publisher":{"@id":"https:\/\/euskadi.verdesequo.es\/EU\/#organization"}}]},"og:locale":"en_US","og:site_name":"EQUO Euskadi","og:type":"article","og:title":"Argazkia3618 | EQUO Berdeak Euskadi","og:url":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/","og:image":"https:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2020\/03\/logoredes.png","og:image:secure_url":"https:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2020\/03\/logoredes.png","article:published_time":"2013-06-30T08:40:49+00:00","article:modified_time":"2013-06-30T08:40:49+00:00","twitter:card":"summary_large_image","twitter:site":"@EquoBerdeak","twitter:title":"Argazkia3618 | EQUO Berdeak Euskadi","twitter:image":"http:\/\/euskadi.partidoequo.es\/wp-content\/uploads\/2020\/03\/logoredes.png"},"aioseo_meta_data":{"post_id":"1341","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 09:04:32","updated":"2025-06-04 02:34:34","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/euskadi.verdesequo.es\/EU\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArgazkia3618\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/euskadi.verdesequo.es\/EU"},{"label":"Argazkia3618","link":"https:\/\/euskadi.verdesequo.es\/EU\/2013\/06\/30\/equo-euskadi-revindica-el-mantenimiento-de-la-ganaderia-extensiva-y-la-recuperacion-y-puesta-en-valor-de-los-ancestrales-caminos-pastoriles\/argazkia3618\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618-300x225.jpg 300w, https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2592,"height":1944,"file":"2013\/06\/Argazkia3618.jpg","sizes":{"thumbnail":{"file":"Argazkia3618-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618-150x150.jpg"},"medium":{"file":"Argazkia3618-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618-300x225.jpg"},"large":{"file":"Argazkia3618-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618-1024x768.jpg"},"full":{"file":"Argazkia3618.jpg","width":2592,"height":1944,"mime_type":"image\/jpeg","source_url":"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"X2-00","caption":"","created_timestamp":1371899925,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":1334,"source_url":"https:\/\/euskadi.verdesequo.es\/wp-content\/uploads\/2013\/06\/Argazkia3618.jpg","filename":"Argazkia3618.jpg","filesize":1342982,"_links":{"self":[{"href":"https:\/\/euskadi.verdesequo.es\/EU\/wp-json\/wp\/v2\/media\/1341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euskadi.verdesequo.es\/EU\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/euskadi.verdesequo.es\/EU\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/euskadi.verdesequo.es\/EU\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euskadi.verdesequo.es\/EU\/wp-json\/wp\/v2\/comments?post=1341"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1334,"href":"https:\/\/euskadi.verdesequo.es\/EU\/wp-json\/wp\/v2\/posts\/1334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}